{"id":1052,"date":"2024-05-10T08:00:46","date_gmt":"2024-05-10T06:00:46","guid":{"rendered":"https:\/\/www.missionevasion.fr\/blog\/?p=1052"},"modified":"2024-05-10T17:18:46","modified_gmt":"2024-05-10T15:18:46","slug":"lescape-game-la-meilleure-maniere-dapprendre","status":"publish","type":"post","link":"https:\/\/www.missionevasion.fr\/blog\/2024\/05\/10\/lescape-game-la-meilleure-maniere-dapprendre\/","title":{"rendered":"L&rsquo;Escape Game : La meilleure mani\u00e8re d&rsquo;apprendre ?"},"content":{"rendered":"<div class='booster-block booster-read-block'>\n                <div class=\"twp-read-time\">\n                \t<i class=\"booster-icon twp-clock\"><\/i> <span>Temps de lecture :<\/span>3 Minute(s), 32 Secondes(s)                <\/div>\n\n            <\/div><p><span style=\"color: #ffffff;\">Pourquoi faire des Escape Game en cours favoriserait l&rsquo;apprentissage et serait un tr\u00e8s bon outil p\u00e9dagogique ?<\/span><\/p>\n<p style=\"text-align: left;\" align=\"CENTER\"><span style=\"color: #ffffff;\">Les Escape Games sont souvent tr\u00e8s engageants car ils plongent les \u00e9l\u00e8ves dans des sc\u00e9narios immersifs qui stimulent leur curiosit\u00e9 et leur d\u00e9sir de r\u00e9soudre des \u00e9nigmes pour atteindre un objectif commun : s&rsquo;\u00e9chapper. De plus ils <span style=\"font-family: S hne, ui-sans-serif, system-ui, apple-system, Segoe UI, Roboto, Ubuntu, Cantarell, Noto Sans, sans-serif, Helvetica Neue, Arial, Apple Color Emoji, Segoe UI Emoji, Segoe UI Symbol, Noto Color Emoji;\"><span style=\"font-size: medium;\">n\u00e9cessitent une participation active des \u00e9l\u00e8ves, les encourageant \u00e0 r\u00e9fl\u00e9chir, \u00e0 r\u00e9soudre des probl\u00e8mes et \u00e0 prendre des d\u00e9cisions en temps r\u00e9el, ce qui favorise un apprentissage plus profond et durable que la simple \u00e9coute de cours magistraux.<\/span><\/span><\/span><\/p>\n<p style=\"text-align: left;\" align=\"CENTER\"><span style=\"color: #ffffff;\">Les Escapes Game <span style=\"font-family: S hne, ui-sans-serif, system-ui, apple-system, Segoe UI, Roboto, Ubuntu, Cantarell, Noto Sans, sans-serif, Helvetica Neue, Arial, Apple Color Emoji, Segoe UI Emoji, Segoe UI Symbol, Noto Color Emoji;\"><span style=\"font-size: medium;\">sont souvent con\u00e7us pour \u00eatre jou\u00e9s en \u00e9quipe, ce qui favorise la collaboration et le travail d&rsquo;\u00e9quipe. Les \u00e9l\u00e8ves doivent communiquer, partager des id\u00e9es et coordonner leurs efforts pour r\u00e9ussir \u00e0 s&rsquo;\u00e9chapper, renfor\u00e7ant ainsi leurs comp\u00e9tences sociales et leurs capacit\u00e9s \u00e0 travailler ensemble.<\/span><\/span><\/span><\/p>\n<p style=\"text-align: left;\" align=\"CENTER\"><span style=\"color: #ffffff;\"><span style=\"font-family: S hne, ui-sans-serif, system-ui, apple-system, Segoe UI, Roboto, Ubuntu, Cantarell, Noto Sans, sans-serif, Helvetica Neue, Arial, Apple Color Emoji, Segoe UI Emoji, Segoe UI Symbol, Noto Color Emoji;\"><span style=\"font-size: medium;\">Les \u00e9nigmes et les d\u00e9fis exigent souvent une pens\u00e9e critique et cr\u00e9ative pour \u00eatre r\u00e9solus. Les \u00e9l\u00e8ves doivent analyser les informations disponibles, faire des d\u00e9ductions logiques et trouver des solutions innovantes pour progresser dans le jeu.<\/span><\/span><\/span><\/p>\n<p style=\"text-align: left;\" align=\"CENTER\"><span style=\"color: #ffffff;\"><span style=\"font-family: S hne, ui-sans-serif, system-ui, apple-system, Segoe UI, Roboto, Ubuntu, Cantarell, Noto Sans, sans-serif, Helvetica Neue, Arial, Apple Color Emoji, Segoe UI Emoji, Segoe UI Symbol, Noto Color Emoji;\"><span style=\"font-size: medium;\">Etant donn\u00e9 qu&rsquo;un jeu d&rsquo;\u00e9vasion est g\u00e9n\u00e9ralement limit\u00e9 dans le temps, cela permettrait\u00a0<\/span><\/span> <span style=\"font-family: S hne, ui-sans-serif, system-ui, apple-system, Segoe UI, Roboto, Ubuntu, Cantarell, Noto Sans, sans-serif, Helvetica Neue, Arial, Apple Color Emoji, Segoe UI Emoji, Segoe UI Symbol, Noto Color Emoji;\"><span style=\"font-size: medium;\">aux \u00e9l\u00e8ves de d\u00e9velopper leurs comp\u00e9tences en gestion du temps et en prise de d\u00e9cision sous pression, des comp\u00e9tences essentielles dans de nombreuses situations de la vie r\u00e9elle.<\/span><\/span> La nature ludique et comp\u00e9titive des Escape Games peut renforcer la motivation intrins\u00e8que des \u00e9l\u00e8ves \u00e0 participer activement \u00e0 l&rsquo;apprentissage, en les incitant \u00e0 relever des d\u00e9fis et \u00e0 atteindre des objectifs sp\u00e9cifiques.<\/span><\/p>\n<p style=\"text-align: left;\"><span style=\"color: #ffffff;\">En int\u00e9grant des Escape Games dans l&rsquo;enseignement, les enseignants peuvent donc cr\u00e9er des exp\u00e9riences d&rsquo;apprentissage dynamiques, originales et stimulantes qui captivent les \u00e9l\u00e8ves tout en renfor\u00e7ant une vari\u00e9t\u00e9 de comp\u00e9tences essentielles pour leur r\u00e9ussite acad\u00e9mique et leur d\u00e9veloppement personnel.<\/span><\/p>\n<p><span style=\"color: #ffffff;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1056\" src=\"https:\/\/www.missionevasion.fr\/blog\/wp-content\/uploads\/2024\/05\/lock-academy-escape-game-paris-tres-cher-lock-hero.jpg\" alt=\"Escape Game avec une \u00e9tudiante\" width=\"1920\" height=\"805\" srcset=\"https:\/\/www.missionevasion.fr\/blog\/wp-content\/uploads\/2024\/05\/lock-academy-escape-game-paris-tres-cher-lock-hero.jpg 1920w, https:\/\/www.missionevasion.fr\/blog\/wp-content\/uploads\/2024\/05\/lock-academy-escape-game-paris-tres-cher-lock-hero-300x126.jpg 300w, https:\/\/www.missionevasion.fr\/blog\/wp-content\/uploads\/2024\/05\/lock-academy-escape-game-paris-tres-cher-lock-hero-1024x429.jpg 1024w, https:\/\/www.missionevasion.fr\/blog\/wp-content\/uploads\/2024\/05\/lock-academy-escape-game-paris-tres-cher-lock-hero-768x322.jpg 768w, https:\/\/www.missionevasion.fr\/blog\/wp-content\/uploads\/2024\/05\/lock-academy-escape-game-paris-tres-cher-lock-hero-1536x644.jpg 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #ffffff;\">Alors c&rsquo;est bien beau mais comment mettre en place un Escape Game dans une salle de classe ?<\/span><\/p>\n<p><span style=\"color: #ffffff;\">Evidemment la question est compliqu\u00e9e car nos \u00e9coles ont rarement un budget pour ce genre d&rsquo;activit\u00e9, n\u00e9anmoins il existe plusieurs astuces afin de rendre les cours plus \u00ab\u00a0immersifs\u00a0\u00bb<\/span><\/p>\n<p><span style=\"color: #ffffff;\">D\u00e9j\u00e0 la lumi\u00e8re d&rsquo;une salle peut \u00eatre am\u00e9nag\u00e9e, rajouter une lumi\u00e8re de chevet sur le bureau du professeur, \u00e9teignez toutes les autres et vous voil\u00e0 en face de Sherlock Holmes qui n&rsquo;attend que ses \u00e9l\u00e8ves pour menez \u00e0 bien son enqu\u00eate !<\/span><\/p>\n<p><span style=\"color: #ffffff;\">Sans parler de costumes, une vieille paire de lunettes, un chapeau et vous voil\u00e0 d\u00e9tective !<\/span><\/p>\n<p><span style=\"color: #ffffff;\">Visuellement, les \u00e9l\u00e8ves seront d\u00e9j\u00e0 dans l&rsquo;histoire mais il manque un point important : la musique ! Et alors l\u00e0 rien de plus simple. Il suffit juste d&rsquo;aller sur Youtube et de chercher un fond sonore qui colle \u00e0 votre th\u00e8me. L&rsquo;utilisation de ses contenus est 100% gratuits.<\/span><\/p>\n<p><span style=\"color: #ffffff;\">On remarque que les joueurs d&rsquo;Escape Game ne s&rsquo;attardent que rarement sur le th\u00e8me de la salle qu&rsquo;ils viennent de faire. Ce qui les marquent le plus ce sont les \u00e9nigmes auxquelles ils se sont heurt\u00e9s. \u00c0 noter que tr\u00e8s souvent les sc\u00e9narios les plus simples sont les meilleurs surtout quand on y ajoute des personnages caricaturaux !<\/span><\/p>\n<p><span style=\"color: #ffffff;\">L&rsquo;important est de cr\u00e9\u00e9 une histoire ou participants (joueurs ou \u00e9l\u00e8ves) vivent des \u00e9motions.<\/span><\/p>\n<p><span style=\"color: #ffffff;\">En sachant que les \u00e9motions qui marqueront le plus les joueurs sont la surprise, l&rsquo;euphorie et la peur.<\/span><\/p>\n<p><span style=\"color: #ffffff;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-224\" src=\"https:\/\/www.missionevasion.fr\/blog\/wp-content\/uploads\/2020\/11\/18-scaled.jpg\" alt=\"Salle du PC S\u00e9curit\u00e9 \u00e0 Lyon\" width=\"2560\" height=\"1707\" srcset=\"https:\/\/www.missionevasion.fr\/blog\/wp-content\/uploads\/2020\/11\/18-scaled.jpg 2560w, https:\/\/www.missionevasion.fr\/blog\/wp-content\/uploads\/2020\/11\/18-300x200.jpg 300w, https:\/\/www.missionevasion.fr\/blog\/wp-content\/uploads\/2020\/11\/18-1024x683.jpg 1024w, https:\/\/www.missionevasion.fr\/blog\/wp-content\/uploads\/2020\/11\/18-768x512.jpg 768w, https:\/\/www.missionevasion.fr\/blog\/wp-content\/uploads\/2020\/11\/18-1536x1024.jpg 1536w, https:\/\/www.missionevasion.fr\/blog\/wp-content\/uploads\/2020\/11\/18-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #ffffff;\">Lorsque vous lancer quelqu&rsquo;un dans un univers il va s&rsquo;y pr\u00e9parer mentalement. Par exemple dans notre aventure <a style=\"color: #ffffff;\" href=\"https:\/\/www.missionevasion.fr\/missions-descape-game-lyon\/excursion-carcerale\/\">\u00ab\u00a0Excursion Carc\u00e9rale\u00a0\u00bb<\/a>. Les joueurs rendre les yeux band\u00e9es et une fois dans la prison ils sentent des odeurs propres \u00e0 la prison. En r\u00e9alit\u00e9 il n&rsquo;y a aucune odeur rajout\u00e9e.<\/span><\/p>\n<p>Nous insistons sur la surprise ! Faire venir un intervenant pendant un cours cr\u00e9era un moment unique. Ca peut \u00eatre un com\u00e9diens ou un autre professeur ? Pourquoi pas juste int\u00e9grer un \u00e9l\u00e8ve qui aurait un r\u00f4le pr\u00e9cis ?<\/p>\n<p>Il y a une infinit\u00e9 de mani\u00e8re de rendre les cours plus \u00ab\u00a0immersif\u00a0\u00bb, avec un peu de temps et de pr\u00e9paration.<\/p>\n<p>Bref vous l&rsquo;aurez compris, \u00eatre Game Master c&rsquo;est vendre du r\u00eave et \u00eatre professeur c&rsquo;est donner les cl\u00e9s pour pouvoir vivre son r\u00eave, alors une chose est s\u00fbr : <em>Si les professeurs prennent plus de plaisir, les \u00e9tudiants en prendront aussi.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><em>Nous remercions l&rsquo;Universit\u00e9 Lyon 2, d&rsquo;avoir organis\u00e9 un Podcast audio autour de ce sujet. Merci aux professeurs Elsa Laneyrie et Nicolas Baltenneck pour leur invitation.<\/em><\/p>\n<p><em>Nous remercions \u00e9galement la \u00ab\u00a0<a href=\"https:\/\/lockacademy.com\/\">Lock Academy\u00a0\u00bb<\/a> de Paris pour les cr\u00e9dits sur la photo.<\/em><\/p>\n<p>&nbsp;<\/p>\n        <div class=\"booster-block booster-reactions-block\">\n            <div class=\"twp-reactions-icons\">\n                \n                <div class=\"twp-reacts-wrap\">\n                    <a react-data=\"be-react-1\" post-id=\"1052\" class=\"be-face-icons un-reacted\" href=\"javascript:void(0)\">\n                        <img decoding=\"async\" src=\"https:\/\/www.missionevasion.fr\/blog\/wp-content\/plugins\/booster-extension\/\/assets\/icon\/happy.svg\" alt=\"Happy\">\n                    <\/a>\n                    <div class=\"twp-reaction-title\">\n                        Happy                    <\/div>\n                    <div class=\"twp-count-percent\">\n                                                    <span style=\"display: none;\" class=\"twp-react-count\">0<\/span>\n                        \n                                                <span class=\"twp-react-percent\"><span>0<\/span> %<\/span>\n                                            <\/div>\n                <\/div>\n\n                <div class=\"twp-reacts-wrap\">\n                    <a react-data=\"be-react-2\" post-id=\"1052\" class=\"be-face-icons un-reacted\" href=\"javascript:void(0)\">\n                        <img decoding=\"async\" src=\"https:\/\/www.missionevasion.fr\/blog\/wp-content\/plugins\/booster-extension\/\/assets\/icon\/sad.svg\" alt=\"Sad\">\n                    <\/a>\n                    <div class=\"twp-reaction-title\">\n                        Sad                    <\/div>\n                    <div class=\"twp-count-percent\">\n                                                    <span style=\"display: none;\" class=\"twp-react-count\">0<\/span>\n                                                                        <span class=\"twp-react-percent\"><span>0<\/span> %<\/span>\n                                            <\/div>\n                <\/div>\n\n                <div class=\"twp-reacts-wrap\">\n                    <a react-data=\"be-react-3\" post-id=\"1052\" class=\"be-face-icons un-reacted\" href=\"javascript:void(0)\">\n                        <img decoding=\"async\" src=\"https:\/\/www.missionevasion.fr\/blog\/wp-content\/plugins\/booster-extension\/\/assets\/icon\/excited.svg\" alt=\"Excited\">\n                    <\/a>\n                    <div class=\"twp-reaction-title\">\n                        Excited                    <\/div>\n                    <div class=\"twp-count-percent\">\n                                                    <span style=\"display: none;\" class=\"twp-react-count\">0<\/span>\n                                                                        <span class=\"twp-react-percent\"><span>0<\/span> %<\/span>\n                                            <\/div>\n                <\/div>\n\n                <div class=\"twp-reacts-wrap\">\n                    <a react-data=\"be-react-6\" post-id=\"1052\" class=\"be-face-icons un-reacted\" href=\"javascript:void(0)\">\n                        <img decoding=\"async\" src=\"https:\/\/www.missionevasion.fr\/blog\/wp-content\/plugins\/booster-extension\/\/assets\/icon\/sleepy.svg\" alt=\"Sleepy\">\n                    <\/a>\n                    <div class=\"twp-reaction-title\">\n                        Sleepy                    <\/div>\n                    <div class=\"twp-count-percent\">\n                                                    <span style=\"display: none;\" class=\"twp-react-count\">0<\/span>\n                        \n                                                <span class=\"twp-react-percent\"><span>0<\/span> %<\/span>\n                                            <\/div>\n                <\/div>\n\n                <div class=\"twp-reacts-wrap\">\n                    <a react-data=\"be-react-4\" post-id=\"1052\" class=\"be-face-icons un-reacted\" href=\"javascript:void(0)\">\n                        <img decoding=\"async\" src=\"https:\/\/www.missionevasion.fr\/blog\/wp-content\/plugins\/booster-extension\/\/assets\/icon\/angry.svg\" alt=\"Angry\">\n                    <\/a>\n                    <div class=\"twp-reaction-title\">Angry<\/div>\n                    <div class=\"twp-count-percent\">\n                                                    <span style=\"display: none;\" class=\"twp-react-count\">0<\/span>\n                                                                        <span class=\"twp-react-percent\"><span>0<\/span> %<\/span>\n                        \n                    <\/div>\n                <\/div>\n\n                <div class=\"twp-reacts-wrap\">\n                    <a react-data=\"be-react-5\" post-id=\"1052\" class=\"be-face-icons un-reacted\" href=\"javascript:void(0)\">\n                        <img decoding=\"async\" src=\"https:\/\/www.missionevasion.fr\/blog\/wp-content\/plugins\/booster-extension\/\/assets\/icon\/surprise.svg\" alt=\"Surprise\">\n                    <\/a>\n                    <div class=\"twp-reaction-title\">Surprise<\/div>\n                    <div class=\"twp-count-percent\">\n                                                    <span style=\"display: none;\" class=\"twp-react-count\">0<\/span>\n                                                                        <span class=\"twp-react-percent\"><span>0<\/span> %<\/span>\n                                            <\/div>\n                <\/div>\n\n            <\/div>\n        <\/div>\n\n    ","protected":false},"excerpt":{"rendered":"<p>Pourquoi faire des Escape Game en cours favoriserait l&rsquo;apprentissage et serait un tr\u00e8s bon outil p\u00e9dagogique ? Les Escape Games sont souvent tr\u00e8s engageants car ils plongent les \u00e9l\u00e8ves dans des sc\u00e9narios immersifs qui stimulent leur curiosit\u00e9 et leur d\u00e9sir de r\u00e9soudre des \u00e9nigmes pour atteindre un objectif commun : [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":1056,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-1052","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lunivers-de-lescape-game"],"_links":{"self":[{"href":"https:\/\/www.missionevasion.fr\/blog\/wp-json\/wp\/v2\/posts\/1052","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.missionevasion.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.missionevasion.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.missionevasion.fr\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.missionevasion.fr\/blog\/wp-json\/wp\/v2\/comments?post=1052"}],"version-history":[{"count":4,"href":"https:\/\/www.missionevasion.fr\/blog\/wp-json\/wp\/v2\/posts\/1052\/revisions"}],"predecessor-version":[{"id":1058,"href":"https:\/\/www.missionevasion.fr\/blog\/wp-json\/wp\/v2\/posts\/1052\/revisions\/1058"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.missionevasion.fr\/blog\/wp-json\/wp\/v2\/media\/1056"}],"wp:attachment":[{"href":"https:\/\/www.missionevasion.fr\/blog\/wp-json\/wp\/v2\/media?parent=1052"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.missionevasion.fr\/blog\/wp-json\/wp\/v2\/categories?post=1052"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.missionevasion.fr\/blog\/wp-json\/wp\/v2\/tags?post=1052"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}